{"id":16197,"date":"2020-04-01T13:18:38","date_gmt":"2020-04-01T16:18:38","guid":{"rendered":"https:\/\/paraquenos.com.ar\/?p=16197"},"modified":"2020-08-07T15:37:36","modified_gmt":"2020-08-07T18:37:36","slug":"16197-2","status":"publish","type":"post","link":"https:\/\/paraquenos.com.ar\/pb\/16197-2\/","title":{"rendered":""},"content":{"rendered":"<p>Buenos Aires. 27 de marzo de 2020<\/p>\n<p>VISTO:<br \/>\nLa dif\u00edcil situaci\u00f3n sanitaria a nivel mundial a causa de la pandemia de Coronavirus Covid-19, la que tambi\u00e9n afecta a nuestro pa\u00eds, ha llevado a decretar el DNU 297\/2020 con medidas restrictivas de circulaci\u00f3n.<\/p>\n<p>Las medidas sanitarias que est\u00e1n impartiendo los ministerios de Salud nacional y provinciales.<\/p>\n<p>Que la Organizaci\u00f3n Mundial de la Salud (OMS) ha considerado a los profesionales veterinarios, en el marco de lo descripto como \u201cUNA SALUD\u201d, como \u201cAGENTES DE ATENCION PRIMARIA DE LA SALUD\u201d.<\/p>\n<p>Que los m\u00e9dicos veterinarios son los profesionales mejor capacitados en el control de las zoonosis.<\/p>\n<p>Que los actores del mercado veterinario, resaltando los roles descriptos de los profesionales veterinarios, emitimos nuestra posici\u00f3n frente a los hechos que est\u00e1n sucediendo.<\/p>\n<p>DADO QUE:<br \/>\nLas entidades profesionales que agrupan a Colegios y Consejos Profesionales, FeVA y FECOVET, tenemos la firme convicci\u00f3n que nuestros matriculados ejercen la profesi\u00f3n veterinaria cumpliendo el rol indelegable descripto anteriormente y el juramento de cuidar la salud de los animales y las personas.<\/p>\n<p>La industria de medicamentos representada por sus dos c\u00e1maras, CLAMEVET y CAPROVE y la distribuci\u00f3n de estos, representada por la c\u00e1mara de distribuidores (CADISVET) nos comprometemos a realizar todo el esfuerzo necesario para continuar con el abastecimiento de los medicamentos necesarios para el tratamiento de los pacientes.<\/p>\n<p>Los proveedores de alimentos balanceados para animales, nucleados en nuestra c\u00e1maraCAENA, nos comprometemos a abastecer de alimentos balanceados tanto fisiol\u00f3gicos como de prescripci\u00f3n, a las veterinarias para proveer a los animales la comida diaria.<\/p>\n<p>La Sociedad de Medicina Veterinaria y la Asociaci\u00f3n de Veterinarios Especialistas en Animales de Compa\u00f1\u00eda (AVEACA) como Asociaciones Cient\u00edficas propenden a que sus veterinarios asociados mantengan la atenci\u00f3n de los pacientes y la disponibilidad de alimentos.<\/p>\n<p>CONSIDERAMOS QUE:<br \/>\nTodo lo enunciado se enmarca en el rol social que le ata\u00f1e a la profesi\u00f3n veterinaria, rol reconocido por la OMS que, por una parte, la reconoce como esencial para la salud y, por otra, le otorga una obligaci\u00f3n de cumplir tal deber y responsabilidad profesional como un guardi\u00e1n sanitario en el medio social en el que desarrolla su actividad.<\/p>\n<p>Todo el accionar del conjunto se debe enmarcar en una operatoria que extreme los cuidados y las recomendaciones brindadas por las autoridades sanitarias para el bien de todos sus actores y de la comunidad, promoviendo al mismo tiempo el cuidado de la salud y el bienestar de los animales.<\/p>\n<p>AVEACA \u2013 CADISVET \u2013 CAENA \u2013 CAPROVE \u2013 CLAMEVET \u2013 FECOVET \u2013 FEVA \u2013 SOCIEDAD DE MEDICINA VETERINARIA DE LA REP\u00daBLICA ARGENTINA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires. 27 de marzo de 2020 VISTO: La dif\u00edcil situaci\u00f3n sanitaria a nivel mundial a causa de la pandemia de Coronavirus Covid-19, la que tambi\u00e9n afecta a nuestro pa\u00eds, ha llevado a decretar el DNU 297\/2020 con medidas restrictivas de circulaci\u00f3n. Las medidas sanitarias que est\u00e1n impartiendo los ministerios de Salud nacional y provinciales. Que la Organizaci\u00f3n Mundial de la Salud (OMS) ha considerado a los profesionales veterinarios, en el marco de lo descripto como \u201cUNA SALUD\u201d, como \u201cAGENTES DE ATENCION PRIMARIA DE LA SALUD\u201d. Que los m\u00e9dicos veterinarios son los profesionales mejor capacitados en el control de las zoonosis. Que los actores del mercado veterinario, resaltando los roles descriptos de los profesionales veterinarios, emitimos nuestra posici\u00f3n frente a los hechos que est\u00e1n sucediendo. DADO QUE: Las entidades profesionales que agrupan a Colegios y Consejos Profesionales, FeVA y FECOVET, tenemos la firme convicci\u00f3n que nuestros matriculados ejercen la profesi\u00f3n veterinaria cumpliendo el rol indelegable descripto anteriormente y el juramento de cuidar la salud de los animales y las personas. La industria de medicamentos representada por sus dos c\u00e1maras, CLAMEVET y CAPROVE y la distribuci\u00f3n de estos, representada por la c\u00e1mara de distribuidores (CADISVET) nos comprometemos a realizar todo el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[196],"tags":[],"class_list":["post-16197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relaciones-institucionales"],"acf":[],"_links":{"self":[{"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/posts\/16197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/comments?post=16197"}],"version-history":[{"count":1,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/posts\/16197\/revisions"}],"predecessor-version":[{"id":16199,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/posts\/16197\/revisions\/16199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/media\/16252"}],"wp:attachment":[{"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/media?parent=16197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/categories?post=16197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paraquenos.com.ar\/pb\/wp-json\/wp\/v2\/tags?post=16197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}